{"id":9274,"date":"2021-06-14T15:21:10","date_gmt":"2021-06-14T19:21:10","guid":{"rendered":"http:\/\/hospitaldechillan.cl\/web\/?p=9274"},"modified":"2021-06-14T15:24:04","modified_gmt":"2021-06-14T19:24:04","slug":"tu-tambien-puedes-ser-donante-de-sangre","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/tu-tambien-puedes-ser-donante-de-sangre\/","title":{"rendered":"\u00a1T\u00fa tambi\u00e9n puedes ser donante de sangre!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00bfSab\u00edas qu\u00e9 en \u00d1uble, quienes m\u00e1s donan sangre son las mujeres entre los 20 y 30 a\u00f1os y que casi el 80% de las y los donantes viven en Chill\u00e1n? As\u00ed lo confirma el registro de la Unidad de Medicina Transfusional del Hospital Cl\u00ednico Herminda Mart\u00edn (HCHM). Esta es la realidad de nuestra Regi\u00f3n, que en el segundo a\u00f1o desde el inicio de la pandemia ha anotado un total de 3 mil 087 donaciones hasta mayo. De estas, 45,1% son donaciones altruistas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br> Hoy se conmemora el D\u00eda Mundial del Donante Altruista y Reiterado de Sangre y por esto destacamos tres distintos perfiles de personas que repiten este acto solidario que beneficia  hasta  3 personas y que no tarda m\u00e1s de 30 minutos en su realizaci\u00f3n desde la inscripci\u00f3n, la encuesta de salud y la extracci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong> Quincuag\u00e9sima ocasi\u00f3n para dar vida<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br> <strong>Aaron Flores a sus 33 a\u00f1os<\/strong>, hoy don\u00f3 por quincuag\u00e9sima vez sangre, es decir ha salvado la vida de hasta 150 personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/hospitaldechillan.cl\/web\/wp-content_Hos\/uploads\/2021\/06\/50-donacion-web-640x360.jpg\" alt=\"\" class=\"wp-image-9276\" srcset=\"https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2021\/06\/50-donacion-web-640x360.jpg 640w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2021\/06\/50-donacion-web-768x432.jpg 768w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2021\/06\/50-donacion-web-1200x675.jpg 1200w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2021\/06\/50-donacion-web.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Actualmente, \u00e9l realiza capacitaciones y es Vicesuperintendente de Bomberos en Pinto e instructor voluntario de la Academia Nacional bomberil. \u201cNo anoto en agendas cuando me corresponde ni nada, solo intento tenerlo presente y si no recuerdo la fecha exacta, llamo al Banco de Sangre y ellos me orientan. Siento que mi est\u00edmulo principal proviene de la crianza que me dieron mis abuelos, mediante su ejemplo. Ellos siempre fueron solidarios y me ense\u00f1aron que hab\u00eda que ayudar sin mirar a quien y eso es lo que intento plasmar en mi vida, por eso, comenc\u00e9 a donar de forma regular cada 3 meses\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Paulina Campos,  es enfermera<\/strong>, trabaja en el M\u00f3dulo C del Servicio de Cirug\u00eda Indiferenciada del HCHM y ha donado sangre en 14 ocasiones, iniciando a los 17 a\u00f1os cuando le interes\u00f3 el concepto de ser un donante altruista. Seg\u00fan Paulina comprendi\u00f3 que \u201cla sangre para todos es un recurso renovable y cada 4 meses puedo aportar sin ning\u00fan efecto adverso para m\u00ed y marcar una diferencia importante para quienes lo necesitan, por eso me motivo a realizarlo y a contribuir a mejorar la salud de otras personas\u201d, cont\u00f3. Agreg\u00f3 que \u201cno me sorprende que seamos las mujeres las m\u00e1s generosas, porque seg\u00fan mi opini\u00f3n nos cuesta menos comprometernos con las causas que consideramos importantes. A m\u00ed por ejemplo, me motiva que con ello ayudo a mejorar la salud de los dem\u00e1s\u201d.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La enfermera recalc\u00f3 que la comunidad de \u00d1uble y de todo el pa\u00eds, debe entender que \u201cla donaci\u00f3n es un procedimiento seguro, que causa muy poco dolor y que en la UMT cuentan con todos los resguardos para evitar contagios de Coronavirus. Luego de cada donaci\u00f3n me siento menos ego\u00edsta sabiendo que aporto un peque\u00f1o grano de arena\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br> Una experiencia similar ha vivido <strong>Cosme M\u00e9ndez (48 a\u00f1os) Ingeniero Civil<\/strong>, con  factor RH negativo en su sangre, \u201ccualidad que consiste en que los gl\u00f3bulos rojos carecen de una prote\u00edna en su superficie, que si tienen quienes son RH positivos. Los RH negativos equivalen al 5% de la poblaci\u00f3n, es decir son muy escasos y si adem\u00e1s  pertenecen al grupo O son considerados donantes universales, o sea que las personas con cualquier grupo sangu\u00edneo pueden recibir su sangre\u201d, explic\u00f3 el <strong>Tecn\u00f3logo M\u00e9dico Jefe de la UMT, Sergio Becerra. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br> \u201cComenc\u00e9 a donar hace unos a\u00f1os, cuando a mi pap\u00e1 lo operaron y en ese momento supe cu\u00e1l era mi grupo sangu\u00edneo y lo dif\u00edcil que es encontrar donantes de este tipo y por eso, quise hacerlo de forma peri\u00f3dica para ayudar a esta tan noble acci\u00f3n. Me motiva saber que las personas enfermas de c\u00e1ncer podr\u00e1n realizar sus terapias y tendr\u00e1n disponible el componente sangu\u00edneo que requieren, es decir ayudar en algo a salvar una vida. Adem\u00e1s siento, que mis acciones son un ejemplo para mis dos hijos, por eso les comento cuando lo hago, para que ellos cuando crezcan tambi\u00e9n lo consideren\u201d, acot\u00f3 Cosme. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conoce la historia de tres personas que con frecuencia acuden al Banco de Sangre del Hospital de Chill\u00e1n, reservando en  sus agendas un tiempo cada tres o cuatro meses, para ayudar altruistamente a quienes lo necesitan. <\/p>\n","protected":false},"author":3,"featured_media":9275,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-9274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 18:34:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/9274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=9274"}],"version-history":[{"count":0,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/9274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/9275"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=9274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=9274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=9274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}