{"id":7370,"date":"2020-07-21T16:09:50","date_gmt":"2020-07-21T20:09:50","guid":{"rendered":"http:\/\/hospitaldechillan.cl\/web\/?p=7370"},"modified":"2020-07-21T16:30:47","modified_gmt":"2020-07-21T20:30:47","slug":"hospital-de-chillan-mantiene-partos-integrales-y-lactancia-protegida-en-pandemia","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/hospital-de-chillan-mantiene-partos-integrales-y-lactancia-protegida-en-pandemia\/","title":{"rendered":"Hospital de Chill\u00e1n mantiene partos integrales y lactancia protegida en pandemia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El coronavirus sin duda ha\ncambiado la realidad a la que est\u00e1bamos acostumbrados y ese escenario se repite\nen todos los \u00e1mbitos de la cotidianeidad, como puede ser una atenci\u00f3n de salud\ny m\u00e1s la llegada de un beb\u00e9 a la familia. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el <strong>Servicio de Obstetricia y Ginecolog\u00eda del Hospital Cl\u00ednico Herminda Mart\u00edn (HCHM)<\/strong>, desde marzo y hasta finales de junio, se atendieron alrededor de 700 partos, de los cuales 23 fueron de madres diagnosticadas con Covid-19. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la <strong>Gestora de los Cuidados de Matroner\u00eda del HCHM, Mar\u00eda Teresa Higuera<\/strong> en el Servicio se habilit\u00f3 un sector exclusivo de aislamiento para pacientes diagnosticadas con Covid, cuya estad\u00eda en promedio es de 3 a 4 d\u00edas. La matrona detall\u00f3 que \u201cgracias al incremento de la \u00a0dotaci\u00f3n, en el sector de hospitalizadas y de urgencia, podemos contar con profesionales en dedicaci\u00f3n casi exclusiva a cada caso de madre Covid-19\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La idea en esta dependencia hospitalaria es <strong>mantener pr\u00e1cticas que favorecen emocionalmente al beb\u00e9 y a la madre<\/strong>, como el apego seguro, la lactancia protegida, y el acompa\u00f1amiento en el parto, aunque la mujer padezca Covid-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque el acompa\u00f1amiento en\nel parto se ha reducido de manera considerable, alcanzando actualmente un 42%, continua\npresente, permitiendo que tanto las mam\u00e1s como el ni\u00f1o o ni\u00f1a por nacer\ndisfruten de esta pr\u00e1ctica. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el nacimiento, e \u201cindependiente\nde si la madre tiene o no COVID, se realiza el apego temprano, acercando al\nreci\u00e9n nacido a su mam\u00e1 y en el caso de una gestante positiva se toman todos\nlos resguardos como por ejemplo que el contacto ya no se realiza piel a piel\u201d,\ndestac\u00f3 Higuera. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/hospitaldechillan.cl\/web\/wp-content_Hos\/uploads\/2020\/07\/hospitalizaci\u00f3n-conjunta-640x360.jpg\" alt=\"\" class=\"wp-image-7374\" srcset=\"https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2020\/07\/hospitalizaci\u00f3n-conjunta-640x360.jpg 640w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2020\/07\/hospitalizaci\u00f3n-conjunta-768x432.jpg 768w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2020\/07\/hospitalizaci\u00f3n-conjunta-1200x675.jpg 1200w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2020\/07\/hospitalizaci\u00f3n-conjunta.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, el beb\u00e9 y\nla madre son hospitalizados en conjunto, aunque sin permitir colecho o estar\nlos dos en la misma cama. Por ello, el reci\u00e9n nacido permanece en su cuna a dos\nmetros de distancia de la cama de su madre, desde donde puede mirar a su mam\u00e1\nfortaleciendo as\u00ed el v\u00ednculo entre ambos. La mujer, en tanto, es asistida en\ntodo momento para lactancia y otras atenciones que requiera, dado el riesgo que\nimplica el contacto f\u00edsico en la transmisi\u00f3n del virus. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la hospitalizaci\u00f3n, <strong>la madre por seguridad permanece en todo momento con mascarilla<\/strong>, para de esta manera tambi\u00e9n <strong>posibilitar la lactancia<\/strong>, siguiendo las recomendaciones de la Organizaci\u00f3n Mundial de la Salud, de la Sociedad Chilena de Pediatr\u00eda y los protocolos del Programa Control de Infecciones del HCHM. Higuera sostuvo que \u201caunque la mam\u00e1 sea positiva para COVID, mantenemos la lactancia, porque no hay evidencia concluyente respaldada por protocolos nacionales del Ministerio de Salud, sobre una posible transmisi\u00f3n mediante la leche y si la hay sobre todos los beneficios que reporta al reci\u00e9n nacido y a la madre. Por eso, la hemos denominado <strong>Lactancia Protegida<\/strong>, que significa que la paciente permanece con mascarilla todo el tiempo, especialmente durante la lactancia. El personal le acomoda su beb\u00e9, previo a un lavado de manos, una limpieza de la mama para que pueda estar en lactancia con \u00e9l o ella\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pese a que la pandemia ha modificado las atenciones de salud y adem\u00e1s restringido horarios de visita, la maternidad ha continuado importantes pr\u00e1cticas como el apego seguro, la lactancia protegida y el acompa\u00f1amiento en el parto. <\/p>\n","protected":false},"author":3,"featured_media":7372,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-7370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 03:53:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/7370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=7370"}],"version-history":[{"count":0,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/7370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/7372"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=7370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=7370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=7370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}