{"id":7358,"date":"2020-07-17T09:15:28","date_gmt":"2020-07-17T13:15:28","guid":{"rendered":"http:\/\/hospitaldechillan.cl\/web\/?p=7358"},"modified":"2020-07-17T09:15:29","modified_gmt":"2020-07-17T13:15:29","slug":"cinco-nuevos-ventiladores-mecanicos-se-suman-a-la-red-asistencial-de-nuble","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/cinco-nuevos-ventiladores-mecanicos-se-suman-a-la-red-asistencial-de-nuble\/","title":{"rendered":"Cinco nuevos ventiladores mec\u00e1nicos se suman a la red asistencial de \u00d1uble"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por segunda vez, en menos de una semana, se increment\u00f3 la capacidad hospitalaria de la Regi\u00f3n. En esta ocasi\u00f3n, mediante la llegada de <strong>5 nuevos ventiladores mec\u00e1nicos <\/strong>que permitir\u00e1n aumentar la dotaci\u00f3n de camas cr\u00edticas en \u00d1uble.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los equipos son parte de la primera partida, de un total de <strong>30 financiados con recursos aprobados por el Fondo Nacional de Desarrollo Regional<\/strong>, mediante un proyecto que busca apoyar la adquisici\u00f3n de equipamiento cl\u00ednico en el marco de la pandemia de Covid 19. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>Intendente Mart\u00edn Arrau<\/strong> valor\u00f3 esta nueva medida que robustece la red asistencial local: \u201cEstuvimos en el Hospital Cl\u00ednico Herminda Mart\u00edn, junto al equipo m\u00e9dico, recibiendo los primeros cinco respiradores mec\u00e1nicos de un total de 30 que fueron adquiridos gracias a la colaboraci\u00f3n del Gobierno Regional de \u00d1uble y al compromiso de nuestros consejeros regionales, para que cada habitante de la regi\u00f3n est\u00e9 m\u00e1s tranquilo. El esfuerzo humano en el \u00e1rea de la salud est\u00e1 acompa\u00f1\u00e1ndonos d\u00eda a d\u00eda como lo hemos visto en estos cuatro meses de crisis sanitaria, pero ahora se suman estas herramientas de \u00faltima tecnolog\u00eda para dar m\u00e1s tranquilidad a nuestros habitantes\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/hospitaldechillan.cl\/web\/wp-content_Hos\/uploads\/2020\/07\/ventiladores-g-640x360.jpg\" alt=\"\" class=\"wp-image-7360\" srcset=\"https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2020\/07\/ventiladores-g-640x360.jpg 640w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2020\/07\/ventiladores-g-768x432.jpg 768w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2020\/07\/ventiladores-g-1200x675.jpg 1200w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2020\/07\/ventiladores-g.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el <strong>director del Servicio de Salud \u00d1uble, Ricardo S\u00e1nchez<\/strong>, explic\u00f3 que \u201clos nuevos ventiladores llegan a reforzar la red integrada Covid 19, espec\u00edficamente, la <strong>Unidad de Cuidados Intensivos (UCI)<\/strong> del Hospital Cl\u00ednico Herminda Mart\u00edn que tiene la mayor capacidad instalada en la Regi\u00f3n, para atender pacientes que necesitan de tratamiento intensivo mientras cursan los momentos m\u00e1s duros de la enfermedad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAgradecemos nuevamente el\napoyo del Gobierno Regional que una vez m\u00e1s contribuye a incrementar aumentar la\ncantidad de camas con ventilaci\u00f3n mec\u00e1nica, para atender a quienes m\u00e1s lo\nnecesitan\u201d, sostuvo el Director del SS\u00d1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cEs nuestro deber apoyar con\nlos recursos\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la actividad, el <strong>presidente del Consejo Regional, Arnoldo Jim\u00e9nez <\/strong>destac\u00f3 el trabajo que realiza la red asistencial y reiter\u00f3 su compromiso con la salud p\u00fablica \u00d1uble. \u00abMuy contento de participar y constatar en terreno la llegada de cinco nuevos ventiladores gracias a los recursos que han sido aprobados por el Consejo Regional para apoyar a salud en el combate de la pandemia\u00bb, expres\u00f3 Jim\u00e9nez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cRealmente satisfecho de poder aportar\ny reconocer el enorme papel que realiza el personal sanitario; para estar al\nfrente de un problema tan delicado como este, se necesita un tremendo\ncompromiso, de manera que es nuestro deber colaborar y alegrarnos porque los\nequipos que se ocuparon, de acuerdo a lo que nos se\u00f1alaban los m\u00e9dicos, son de\nprimera categor\u00eda; son de primera l\u00ednea\u00bb, a\u00f1adi\u00f3 el presidente del CORE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de los primeros, de un total de 30 equipos de este tipo adquiridos por el Gobierno Regional para apoyar a los hospitales locales en el marco de la pandemia.<\/p>\n","protected":false},"author":3,"featured_media":7359,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-7358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 05:09:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/7358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=7358"}],"version-history":[{"count":0,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/7358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/7359"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=7358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=7358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=7358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}