{"id":6901,"date":"2020-03-20T14:34:24","date_gmt":"2020-03-20T18:34:24","guid":{"rendered":"http:\/\/hospitaldechillan.cl\/web\/?p=6901"},"modified":"2020-03-20T14:42:29","modified_gmt":"2020-03-20T18:42:29","slug":"ministerio-de-salud-anuncio-nuevas-medidas-sanitarias-para-enfrentar-el-coronavirus","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/ministerio-de-salud-anuncio-nuevas-medidas-sanitarias-para-enfrentar-el-coronavirus\/","title":{"rendered":"Ministerio de Salud anunci\u00f3 nuevas medidas sanitarias para enfrentar el Coronavirus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El <strong>ministro de Salud, Jaime Ma\u00f1alich<\/strong> entreg\u00f3  el nuevo reporte de contagios de Coronavirus (Covid-19). En un d\u00eda se sumaron 92 nuevos casos, aumentando a 434 el n\u00famero de personas contagiadas en el pa\u00eds. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el objetivo de ayudar a disminuir la concentraci\u00f3n de personas y evitar &nbsp;la diseminaci\u00f3n de este virus, \u201cel Presidente nos ha pedido determinar a partir del d\u00eda de hoy el cierre, en todo el territorio nacional por un periodo indefinido, de los siguientes tipos de locales: cines; teatros, restaurantes, pubs, discotecas, eventos deportivos independientes que congreguen p\u00fablico\u201d, inform\u00f3 el ministro Ma\u00f1alich. Medida que comenzar\u00e1 a regir a partir de las 00.00 de esta noche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas acciones se complementan a la suspensi\u00f3n de clases de colegios, la aplicaci\u00f3n de cuarentena en algunos lugares del pa\u00eds, como Caleta Tortel e Isla de Pascua. Al respecto de este \u00faltimo, la autoridad explic\u00f3 que la cuarentena \u201cconsiste en aislar a personas que est\u00e1n con una enfermedad o que tienen un alto riesgo de desarrollarla,\u00a0 para que esa infecci\u00f3n no se contagie al resto de la comunidad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se suman a las medidas mencionadas  por el ministro Jaime Ma\u00f1alich, las siguientes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Aduanas sanitarias en 8 regiones\ndel pa\u00eds para proteger a las regiones que est\u00e1n libres del virus. Hoy se suma\nla aduana a la localidad de Puerto Williams y de Chilo\u00e9, por posibles\nsospechosos de contagio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; 31 laboratorios con capacidad para realizar 4 mil examenes con capacidad de ampliaci\u00f3n a 9 mil en las ciudades de Antofagasta, Valpara\u00edso, Santiago, Talca y Valdivia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al mismo tiempo, la subsecretaria de Salud P\u00fablica, Paula Daza, entreg\u00f3 las cifras de vacunaci\u00f3n contra la influenza. En estos 3 d\u00edas, 2.864.494 personas han sido vacunadas, que corresponden al 38,5% de la poblaci\u00f3n de riesgo (adultos mayores 44% y enfermos cr\u00f3nicos 57%).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre algunas de las disposiciones destacan el cierre de cines, teatros, restaurantes, pubs, discotheques y eventos deportivos independientes, de manera indefinida. <\/p>\n","protected":false},"author":3,"featured_media":6903,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[4,1],"tags":[],"class_list":["post-6901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sin-categoria"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 10:23:59","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/6901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=6901"}],"version-history":[{"count":0,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/6901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/6903"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=6901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=6901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=6901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}