{"id":6560,"date":"2020-03-02T15:46:27","date_gmt":"2020-03-02T19:46:27","guid":{"rendered":"http:\/\/hospitaldechillan.cl\/web\/?p=6560"},"modified":"2020-03-03T11:41:42","modified_gmt":"2020-03-03T15:41:42","slug":"en-terreno-y-participativamente-el-hospital-de-chillan-elabora-la-cuenta-publica-anual","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/en-terreno-y-participativamente-el-hospital-de-chillan-elabora-la-cuenta-publica-anual\/","title":{"rendered":"En terreno y participativamente el Hospital de Chill\u00e1n elabora la Cuenta P\u00fablica anual"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hasta Coelemu se trasladaron hoy los <strong>directivos del Hospital Cl\u00ednico Herminda Mart\u00edn<\/strong> para iniciar la preparaci\u00f3n de la Cuenta P\u00fablica, correspondiente a la gesti\u00f3n 2019. La iniciativa, descentralizada y participativa, considera visitar en marzo las comunas con <strong>Hospitales Comunitarios<\/strong> para dialogar con la comunidad sobre los avances y desaf\u00edos del establecimiento de referencia regional y conocer las inquietudes y necesidades de atenci\u00f3n de boca de los propios usuarios. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La <a aria-label=\"cuenta p\u00fablica  (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/hospitaldechillan.cl\/web\/contenidos\/cpublica\/\" target=\"_blank\" rel=\"noreferrer noopener\">cuenta p\u00fablica <\/a>es un ejercicio de transparencia para garantizar el control ciudadano sobre el uso de los recursos p\u00fablicos, la toma de decisiones y los resultados de gesti\u00f3n hospitalaria. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEste a\u00f1o quisimos innovar y trasladarnos a terreno, donde residen una parte importante de nuestros usuarios. Partimos por la comuna m\u00e1s alejada de Chill\u00e1n, <a aria-label=\"Coelemu (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/hospitaldecoelemu.cl\/portal\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Coelemu<\/strong><\/a><strong>, pero tambi\u00e9n estaremos en <\/strong><a aria-label=\"Quirihue (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/hospitaldequirihue.cl\/portal\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Quirihue<\/strong><\/a><strong>, <\/strong><a aria-label=\"Bulnes (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/hospitaldebulnes.cl\/portal\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Bulnes<\/strong><\/a><strong>, <\/strong><a aria-label=\"Yungay (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/hospitaldeyungay.cl\/portal\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Yungay<\/strong><\/a><strong>, <\/strong><a aria-label=\"El Carmen (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/hospitaldeelcarmen.cl\/portal\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>El Carmen<\/strong><\/a><strong> y <\/strong><a aria-label=\"San Carlos, (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/hospitalsancarlos.cl\/portal\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>San Carlos,<\/strong><\/a> para exponer directamente a la comunidad los resultados de la gesti\u00f3n hospitalaria, las \u00e1reas con buen cumplimiento y aquellas en las que es necesario mejorar\u201d, coment\u00f3 el <strong>director del Herminda Mart\u00edn, Luis Alberto P\u00e9rez Ojeda.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo m\u00e1s importante, es que en conjunto con la comunidad priorizaremos aquellos desaf\u00edos u oportunidades de mejora que hemos recogido en di\u00e1logos ciudadanos, reuniones o a trav\u00e9s de las OIRS, para implementar este a\u00f1o iniciativas concretas, que se traduzcan en un mejor servicio y m\u00e1s satisfacci\u00f3n usuaria\u201d, precis\u00f3 el directivo. &nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/hospitaldechillan.cl\/web\/wp-content_Hos\/uploads\/2020\/03\/PHOTO-2020-03-02-16-16-39-640x480.jpg\" alt=\"\" class=\"wp-image-6566\" srcset=\"https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2020\/03\/PHOTO-2020-03-02-16-16-39-640x480.jpg 640w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2020\/03\/PHOTO-2020-03-02-16-16-39-768x576.jpg 768w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2020\/03\/PHOTO-2020-03-02-16-16-39.jpg 1040w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta del Consejo de Desarrollo del Hospital de Coelemu, Valeria Mendoza, se\u00f1al\u00f3 que \u00abcomo dirigentes siempre hemos estado a la vanguardia con las instancias que nos brinda la red de salud y el Hospital de Chill\u00e1n. Encontramos genial que el director del Hospital Base de \u00d1uble, se encuentre en nuestras instalaciones y vea in situ la realidad que tiene nuestro establecimiento y nos pueda apoyar en futuros proyectos. Encontramos que es muy bueno que se traslade a terreno, eso es fabuloso, que conozca nuestra realidad.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La modalidad de esta cuenta p\u00fablica en terreno considera el encuentro con los consejos de usuarios de los <strong>cinco hospitales comunitarios de la Regi\u00f3n de \u00d1uble m\u00e1s el Hospital de San Carlos<\/strong>. Tras la presentaci\u00f3n del balance de gesti\u00f3n,&nbsp; el <strong>Director del Hospital Cl\u00ednico Herminda Mart\u00edn<\/strong> escucha las preguntas de los participantes, quienes posteriormente priorizan las iniciativas que el establecimiento &nbsp;debe implementar este a\u00f1o para la atenci\u00f3n en el \u00e1rea de urgencia, en el centro de especialidades o de hospitalizaci\u00f3n. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En di\u00e1logos con los consejos de usuarios de los Hospitales Comunitarios el principal establecimiento de salud de \u00d1uble organiza la rendici\u00f3n de su balance 2019.<\/p>\n","protected":false},"author":3,"featured_media":6571,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4,1],"tags":[],"class_list":["post-6560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sin-categoria"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 02:14:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/6560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=6560"}],"version-history":[{"count":0,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/6560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/6571"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=6560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=6560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=6560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}