{"id":5853,"date":"2019-07-11T08:52:33","date_gmt":"2019-07-11T12:52:33","guid":{"rendered":"http:\/\/hospitaldechillan.cl\/web\/?p=5853"},"modified":"2019-07-15T08:59:30","modified_gmt":"2019-07-15T12:59:30","slug":"especialista-aconseja-extremar-precauciones-para-prevenir-quemaduras-infantiles","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/especialista-aconseja-extremar-precauciones-para-prevenir-quemaduras-infantiles\/","title":{"rendered":"Especialista aconseja extremar precauciones para prevenir quemaduras infantiles"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La curiosidad de los m\u00e1s peque\u00f1os muchas veces no tiene l\u00edmites y en ocasiones, esto puede llevarlos a no dimensionar los riesgos, tal como sucede en los accidentes por<strong> quemaduras,<\/strong> que en <strong>\u00e9poca invernal tienen un aumento de casi un 40% en comparaci\u00f3n con otras estaciones<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante una quemadura hay que tener en cuenta la gravedad de la lesi\u00f3n, la cual est\u00e1 determinada por grados (primero, segundo y tercero) y el lugar del cuerpo donde ocurre. Tal\u00a0 como explic\u00f3 la <strong>m\u00e9dico jefa del<a href=\"https:\/\/hospitaldechillan.cl\/web\/organizacion\/cr\/pediatria\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" Servicio de Cirug\u00eda Infantil del\u00a0 Hospital Cl\u00ednico Herminda Mart\u00edn de Chill\u00e1n (abre en una nueva pesta\u00f1a)\"> Servicio de Cirug\u00eda Infantil del\u00a0 Hospital Cl\u00ednico Herminda Mart\u00edn de Chill\u00e1n<\/a>, Dra. Sandra Flores<\/strong>, este tipo de accidente es m\u00e1s frecuente en ni\u00f1os menores de dos a\u00f1os, quienes por lo general \u201cresultan heridos en cabeza, tronco y extremidades, \u00a0y dependiendo de la gravedad o complejidad se determina la manera en que se aplicar\u00e1 el tratamiento con los usuarios\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alguna de las principales recomendaciones para evitar este\ntipo de accidentes contemplan instalar barreras alrededor de las estufas para\nimpedir que el ni\u00f1o se acerque, mantener el hervidor fuera del alcance de los\npeque\u00f1os, idealmente con un cable corto, adem\u00e1s de fijar la cocina a los muros\npara prevenir volcamientos de ella. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Dra. Flores enfatiz\u00f3 en el cuidado y atenci\u00f3n de los adultos\npara evitar este tipo de situaciones y en caso de suceder que un ni\u00f1o se queme,\nel principal consejo es acudir a un centro de salud cercano al hogar para que\nse eval\u00fae la gravedad de la lesi\u00f3n y se inicie el tratamiento m\u00e9dico. No\nobstante, precis\u00f3 que \u201csi la quemadura fue producto de derrame de l\u00edquidos\ncalientes, es aconsejable verter agua fr\u00eda sobre la piel da\u00f1ada, retirar la\nropa en caso de ser posible y no aplicar nada sobre la herida, mientras que si\nla lesi\u00f3n fue hecha por fuego o contacto con superficies calientes, no se\nretire la vestimenta y se cubra la zona con gasa o pa\u00f1o limpio antes de\ndirigirse al servicio de urgencia m\u00e1s cercano\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de las quemaduras de mayor gravedad, se hacen\nlimpiezas quir\u00fargicas en Pabell\u00f3n y luego deben ser hospitalizados para nuevas\nintervenciones ya sea para realizar curaciones o en casos m\u00e1s extremos,\nrealizar injertos de piel. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la especialista, <strong>el promedio de d\u00edas hospitalizaci\u00f3n es cercano a las dos semanas, dependiendo de la evoluci\u00f3n de cada usuario.\u00a0 Tras esto hay un proceso de rehabilitaci\u00f3n<\/strong>, que finaliza \u201ccuando el paciente termina de crecer, para evaluar y hacer seguimiento a las lesiones y tener la certeza de que las secuelas ocasionados no han derivado en un da\u00f1o funcional o est\u00e9tico muy severo, por eso, hacemos un llamado a los padres y cuidadores, de extremar las precauciones y evitar los riesgos que generan los artefactos calientes dentro de nuestros hogares\u201d, resalt\u00f3 la cirujano infantil. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pacientes quemados <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el <strong>Hospital Cl\u00ednico Herminda Mart\u00edn durante el invierno, se hospitalizan en promedio 5 ni\u00f1os por semana<\/strong> debido a quemaduras, siendo en su mayor\u00eda producto de derrame de l\u00edquidos calientes, como en el caso de Antonella (5 a\u00f1os) quien se accident\u00f3 el brazo izquierdo con agua del hervidor y ha estado m\u00e1s de 7 d\u00edas hospitalizada, recibiendo los cuidados necesarios para mejorar su herida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su madre, Roxana Campos cont\u00f3 que ha habido un&nbsp; avance positivo en la condici\u00f3n de salud de\nAntonella, pero que&nbsp; \u201cel momento del\naccidente fue fuerte, tuve que sacarle la ropa y mojar su bracito, para luego\nllevarla al Hospital y que le hicieran curaciones o limpieza de la herida en el\npabell\u00f3n\u201d.&nbsp; Tras el per\u00edodo de\nhospitalizaci\u00f3n, la ni\u00f1a deber\u00e1 seguir su tratamiento y rehabilitaci\u00f3n en el\nCentro Ambulatorio de Especialidades. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>5 ni\u00f1os son hospitalizados semanalmente por accidentes de este tipo, siendo los m\u00e1s usuales los vinculados a derrames de l\u00edquidos calientes. <\/p>\n","protected":false},"author":3,"featured_media":5855,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:01:59","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/5853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=5853"}],"version-history":[{"count":0,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/5853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/5855"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=5853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=5853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=5853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}