{"id":5052,"date":"2018-11-14T16:20:34","date_gmt":"2018-11-14T20:20:34","guid":{"rendered":"http:\/\/hospitaldechillan.cl\/web\/?p=5052"},"modified":"2018-11-14T16:20:34","modified_gmt":"2018-11-14T20:20:34","slug":"intendente-de-nuble-se-reunio-con-el-consejo-consultivo-de-usuarios-del-hospital-de-chillan","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/intendente-de-nuble-se-reunio-con-el-consejo-consultivo-de-usuarios-del-hospital-de-chillan\/","title":{"rendered":"Intendente de \u00d1uble se reuni\u00f3 con el Consejo Consultivo de Usuarios del Hospital de Chill\u00e1n"},"content":{"rendered":"<p><strong>El Intendente de la Regi\u00f3n, Mart\u00edn Arrau Garc\u00eda Huidobro, particip\u00f3 del Consejo Consultivo de Usuarios (CCU) del Hospital Cl\u00ednico Herminda Mart\u00edn de Chill\u00e1n<\/strong>, oportunidad donde conoci\u00f3 a los consejeros comunitarios de 39 organizaciones que en representaci\u00f3n de la sociedad civil, entregan las preocupaciones, necesidades y propuestas al recinto asistencial, provenientes de los habitantes de \u00d1uble.<\/p>\n<p>Durante la reuni\u00f3n, el Director (s) del Servicio de Salud \u00d1uble, Ricardo S\u00e1nchez Opazo, dio la bienvenida a la autoridad y valor\u00f3 su asistencia a la instancia de participaci\u00f3n ciudadana que sesiona mensualmente en el recinto asistencial local.<\/p>\n<p>\u201cAgradezco la visita del Intendente quien hizo un espacio en su agenda para conocer a los consejeros comunitarios de las\u00a0 organizaciones y participar de la sesi\u00f3n del CCU que ha funcionado de manera ininterrumpida durante 20 a\u00f1os. Adem\u00e1s, destaco la contribuci\u00f3n de nuestros dirigentes quienes, insertos en la estructura organizacional del Hospital, representan las principales inquietudes y necesidades de la comunidad al equipo directivo del Establecimiento\u201d, explic\u00f3.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5054\" src=\"https:\/\/hospitaldechillan.cl\/web\/wp-content_Hos\/uploads\/2018\/11\/web-1-640x360.jpg\" alt=\"web\" width=\"640\" height=\"360\" srcset=\"https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2018\/11\/web-1-640x360.jpg 640w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2018\/11\/web-1-768x432.jpg 768w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2018\/11\/web-1-1200x675.jpg 1200w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2018\/11\/web-1.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>La m\u00e1xima autoridad de \u00d1uble, comparti\u00f3 detalles de los primeros avances de la instalaci\u00f3n de la Regi\u00f3n y dialog\u00f3 con los integrantes del organismo asesor, acerca de sus inquietudes y necesidades. Adem\u00e1s, durante la sesi\u00f3n, en la que participaron las autoridades del HCHM encabezadas por el Director (s) de la Instituci\u00f3n, Dr. Oscar Chac\u00f3n Ib\u00e1\u00f1ez, el Jefe Oficina de Calidad y Seguridad del Paciente, Dr. Rodrigo Avenda\u00f1o Brandeis, expuso sobre el Sistema de Vigilancia de Evento Adversos que cuenta el Hospital y la enfermera supervisora de la Unidad de Emergencia, Aurora Barra Dur\u00e1n, explic\u00f3 el Sistema de Categorizaci\u00f3n en el Selector de Demanda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sesi\u00f3n mensual del \u00f3rgano asesor cont\u00f3 con la presencia de la m\u00e1xima autoridad de la Regi\u00f3n, quien dialog\u00f3 con los representantes de instituciones p\u00fablicas, universidades y voluntariados, entre otros organismos.<\/p>\n","protected":false},"author":3,"featured_media":5053,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 15:32:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/5052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=5052"}],"version-history":[{"count":0,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/5052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/5053"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=5052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=5052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=5052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}