{"id":4997,"date":"2018-10-26T11:43:36","date_gmt":"2018-10-26T15:43:36","guid":{"rendered":"http:\/\/hospitaldechillan.cl\/web\/?p=4997"},"modified":"2018-10-26T13:44:28","modified_gmt":"2018-10-26T17:44:28","slug":"unidad-de-medicina-transfusional-invita-a-migrantes-a-ser-donantes","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/unidad-de-medicina-transfusional-invita-a-migrantes-a-ser-donantes\/","title":{"rendered":"Unidad de Medicina Transfusional invita a migrantes a ser donantes"},"content":{"rendered":"<p>Las Unidades de Medicina Transfusional (UMT) constantemente deben superar desaf\u00edos, como el envejecimiento de la poblaci\u00f3n y la insuficiencia de donantes asociado al aumento de procedimientos quir\u00fargicos que requieren del vital elemento, adem\u00e1s de la escasez de la poblaci\u00f3n con grupo sangu\u00edneo RH negativo que es de tan s\u00f3lo 0.5%. Asimismo, <strong>la inmigraci\u00f3n es el fen\u00f3meno que constituye un nuevo reto, situaci\u00f3n que motiv\u00f3 la exposici\u00f3n del Tecn\u00f3logo M\u00e9dico Sergio Becerra, Jefe de la UMT del Hospital en la tercera versi\u00f3n de la Jornada de Actualizaci\u00f3n de Apoyo Terap\u00e9utico y Diagn\u00f3stico, realizada en el recinto asistencial.<\/strong><\/p>\n<p>Actualmente, cerca de 4 mil ciudadanos extranjeros residen en \u00d1uble, quienes representan un 0,8% del total de la poblaci\u00f3n en la Regi\u00f3n y pueden requerir atenci\u00f3n en el Hospital, ya sea por sufrir un accidente, necesitar de una cirug\u00eda, \u00a0o de atenci\u00f3n en un parto, prestaciones en las que se requieren componentes sangu\u00edneos para su concreci\u00f3n, y aunque la UMT realiza numerosas colectas de sangre, si \u00e9sta no tiene un origen similar podr\u00eda complejizar la transfusi\u00f3n.<\/p>\n<h2><strong>Extranjeros e incompatibilidad sangu\u00ednea<\/strong><\/h2>\n<p><strong>Mediante nuevas tecnolog\u00edas el equipo de la UMT del establecimiento asistencial previene una eventual incompatibilidad sangu\u00ednea producto de una transfusi\u00f3n a un ciudadano con descendencia afroamericana.<\/strong><\/p>\n<p>Tal como aclar\u00f3 Becerra, <strong>los extranjeros no nos pueden causar da\u00f1o, sino que es nuestra sangre la que puede eventualmente perjudicarlos<\/strong>, provocando reacciones inmunol\u00f3gicas.<\/p>\n<p>\u201cLos problemas que pueden presentarse es una reacci\u00f3n hemol\u00edtica y\/o la enfermedad hemol\u00edtica del reci\u00e9n nacido en embarazadas. Esto ocurre porque <strong>el sistema inmunol\u00f3gico del paciente va a detectar ant\u00edgenos que no son propios, es decir c\u00e9lulas que son demasiado distintas, generando anticuerpos lo que puede provocar reacciones adversas a la transfusi\u00f3n<\/strong>\u201d, explic\u00f3 el profesional quien hizo un llamado a la poblaci\u00f3n extranjera a sumarse a estas cruzadas solidarias y a ser donantes altruistas.<\/p>\n<p>Louna Dorvil, quien lleva un a\u00f1o en Chile, valor\u00f3 que profesionales dialoguen sobre la inmigraci\u00f3n y los alcances en salud, pues seg\u00fan coment\u00f3 \u201cmi madre falleci\u00f3 en Hait\u00ed por la falta de donantes de sangre, por lo mismo es muy importante que los extranjeros y la comunidad en general sin importar su nacionalidad realicen este gesto que salvan vidas.\u00a0 Me parece muy bueno que piensen en los inmigrantes, es un acto humano\u201d, expres\u00f3.<\/p>\n<h2><strong>3\u00b0 Jornada de Actualizaci\u00f3n de Apoyo Terap\u00e9utico y Diagn\u00f3stico<\/strong><\/h2>\n<p>Adem\u00e1s de este contingente tema, la tercera versi\u00f3n de la Jornada de Actualizaci\u00f3n de Apoyo Terap\u00e9utico y Diagn\u00f3stico, que se realiz\u00f3 en el Auditorio del HCHM, incluy\u00f3 otras tem\u00e1ticas interesantes. La Doctora Mar\u00eda Loreto Laval, organizadora de la actividad explic\u00f3 que \u201cfue un \u00e9xito la jornada, pues cerca de un centenar de asistentes presenciaron las ponencias de los expositores, dialogaron y aclararon sus dudas en diversas mesas redondas sobre enfoque cl\u00ednico &#8211; financiero de Grupos Relacionados por Diagn\u00f3stico (GRD) que fue expuesto por Silvana Santander coordinadora del Ministerio de Salud, la epidemia de VIH en Chile, el c\u00e1ncer de piel, entre otros\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debido a una eventual incompatibilidad sangu\u00ednea, es preferible que la sangre transfundida a extranjeros corresponda a otra persona de la misma ascendencia para evitar reacciones inmunol\u00f3gicas. <\/p>\n","protected":false},"author":3,"featured_media":4998,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:18:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/4997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=4997"}],"version-history":[{"count":0,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/4997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/4998"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=4997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=4997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=4997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}