{"id":4924,"date":"2018-09-21T15:18:23","date_gmt":"2018-09-21T19:18:23","guid":{"rendered":"http:\/\/hospitaldechillan.cl\/web\/?p=4924"},"modified":"2018-09-24T08:00:29","modified_gmt":"2018-09-24T12:00:29","slug":"como-ponerte-en-forma-y-desintoxicar-tu-cuerpo-tras-las-fiestas-patrias-aqui-7-consejos-nutricionales","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/como-ponerte-en-forma-y-desintoxicar-tu-cuerpo-tras-las-fiestas-patrias-aqui-7-consejos-nutricionales\/","title":{"rendered":"Desintoxica tu cuerpo y ponte en forma tras las Fiestas Patrias, aqu\u00ed 7 consejos nutricionales"},"content":{"rendered":"<p>Se acab\u00f3 la celebraci\u00f3n de las Fiestas Patrias donde la degustaci\u00f3n de nuestra gastronom\u00eda t\u00edpica hizo lo suyo. <strong>Se estima que en promedio los chilenos y chilenas suben entre 2 a 3 kilos de peso<\/strong> entre tanta empanada, terremoto y chorip\u00e1n. Por este motivo, es importante <strong>bajar los kilos de m\u00e1s de manera saludable<\/strong>.<\/p>\n<p>Camila Guti\u00e9rrez Gallegos, nutricionista del Hospital Cl\u00ednico Herminda Mart\u00edn de Chill\u00e1n (HCHM), explic\u00f3 <strong>que de manera progresiva y siguiendo pr\u00e1cticos consejos, aquella dificultosa tarea de ponerse en forma se lograr\u00e1 m\u00e1s f\u00e1cil de lo que se piensa.<\/strong><\/p>\n<h2>Consejos para ponerse en forma despu\u00e9s del 18<\/h2>\n<ol>\n<li><strong>No caer en la desesperaci\u00f3n por bajar de peso:<\/strong> Lograr reducir 2 o 3 kilos es m\u00e1s f\u00e1cil de lo que se cree, pero no es un cometido que se logre en pocos d\u00edas. Lo primero es tomarse las cosas con calma y ser met\u00f3dico.<\/li>\n<li><strong>Dietas extremas<\/strong>: Muchas veces encontramos dietas \u201cmilagrosas\u201d que nos aseguran perder peso en poco tiempo. Sin embargo, este tipo de reg\u00edmenes alimenticios son muy peligrosos debido a las consecuencias posteriores que nos pueden ocasionar como una gastritis o el temido efecto rebote.<\/li>\n<li><strong>Reducir las calor\u00edas<\/strong>: Para lograr que tu cuerpo pueda quemar el exceso de calor\u00edas, consumir una dieta rica en vegetales y carnes blancas o magras son nuestra mejor aliada para equilibrar nuestra alimentaci\u00f3n y compensar el exceso cal\u00f3rico.<\/li>\n<li><strong>Hidratarse correctamente<\/strong>: El agua ayuda a reemplazar las bebidas con az\u00facar y a hidratarse dado sea el caso que se haya consumido alcohol durante el feriado, adem\u00e1s tiene la propiedad de promover la desintoxicaci\u00f3n.<\/li>\n<li><strong>Porciones peque\u00f1as<\/strong>: Reducir el consumo de determinados alimentos ricos en harinas, az\u00facares y sodio, permiten bajar el requerimiento energ\u00e9tico del cuerpo generado por el exceso, como tambi\u00e9n reducir el n\u00famero de calor\u00edas totales. Por esto, se recomienda realizar cuatro comidas al d\u00eda, manteniendo las porciones adecuadas.<\/li>\n<li><strong>Desintoxicarse<\/strong>: Consumir alimentos ricos en fibra, as\u00ed como vegetales de hojas verdes, ayudar\u00e1n a limpiar el exceso de grasa en el cuerpo. Una vez realizado esto se debe retomar a una dieta balanceada.<\/li>\n<li><strong>Ejercitarse<\/strong>: Ning\u00fan tipo de alimento o dieta lograr\u00e1 una p\u00e9rdida de peso por si solo, es necesario combinarlo con sesiones de ejercicio con una duraci\u00f3n m\u00ednima de 30 minutos o cualquier actividad f\u00edsica recreativa.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Deje de lado las \u2018dietas milagrosas\u2019, pues hidrat\u00e1ndose, reduciendo el consumo de calor\u00edas y ejercit\u00e1ndose de manera regular retomar\u00e1 su peso habitual.  <\/p>\n","protected":false},"author":3,"featured_media":4926,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[4,1],"tags":[],"class_list":["post-4924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sin-categoria"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:10:48","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/4924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=4924"}],"version-history":[{"count":0,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/4924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/4926"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=4924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=4924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=4924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}