{"id":4504,"date":"2018-05-22T14:43:21","date_gmt":"2018-05-22T18:43:21","guid":{"rendered":"http:\/\/hospitaldechillan.cl\/web\/?p=4504"},"modified":"2018-05-25T16:01:55","modified_gmt":"2018-05-25T20:01:55","slug":"mas-de-300-personas-con-fisura-labiopalatina-reciben-atencion-integral-en-hospital-de-chillan","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/mas-de-300-personas-con-fisura-labiopalatina-reciben-atencion-integral-en-hospital-de-chillan\/","title":{"rendered":"M\u00e1s de 300 personas con fisura labiopalatina reciben atenci\u00f3n integral en Hospital de Chill\u00e1n"},"content":{"rendered":"<p>Un equipo multidisciplinario controla y brinda atenci\u00f3n funcional y est\u00e9tica a los m\u00e1s de <strong>300 \u00f1ublensinos<\/strong> que presentan <strong>fisura labiopalatina<\/strong>\u00a0(o de labio y paladar). Esta patolog\u00eda es una alteraci\u00f3n en la formaci\u00f3n de las estructuras de la cara, que requiere ser tratada desde el embarazo y hasta que la persona cumple 18 a\u00f1os, a lo menos.<br \/>\n17 profesionales integran el <strong>Comit\u00e9 de Fisurados del Hospital Cl\u00ednico Herminda Mart\u00edn (HCHM)<\/strong>, que est\u00e1 compuesto por otorrinolaring\u00f3logos, <a href=\"https:\/\/hospitaldechillan.cl\/web\/operativo-quirurgico-plastico-permitio-intervenir-a-7-jovenes-y-ninos-de-nuble\/\" target=\"_blank\">cirujanos pl\u00e1sticos y maxilofaciales<\/a>, rehabilitadores orales, odontopediatras, fonoaudi\u00f3logo, psic\u00f3loga infantil, kinesi\u00f3logo y enfermeras, quienes cumplen una funci\u00f3n determinante y conjunta en cada tratamiento.\u00a0Durante el 2017, el \u00e1rea de rehabilitaci\u00f3n entreg\u00f3 4 mil 053 prestaciones.<\/p>\n<h2>\u00a0Acreditados para realizar las cirug\u00edas primarias<\/h2>\n<p>Desde 2014, el Ministerio de Salud acredit\u00f3 al Hospital como <strong>1 de los 10 centros que brindan el tratamiento completo en Chile<\/strong>,\u00a0iniciando desde esa fecha la realizaci\u00f3n de las cirug\u00edas primarias en quienes lo requer\u00edan.<br \/>\n\u201cEl tratamiento comienza con una evaluaci\u00f3n del paciente, educaci\u00f3n y ortopedia pre-quir\u00fargica. La primera cirug\u00eda se llama <strong>Queiloplast\u00eda<\/strong>, su prop\u00f3sito es <strong>cerrar el labio y la fosa nasal afectada por la fisura<\/strong>. Durante este a\u00f1o se han realizado 28 procedimientos, los que si bien son realizados por cirujanos maxilofaciales, requieren el trabajo del equipo de especialistas\u201d, relat\u00f3 el ortodoncista y presidente del Comit\u00e9 de Fisurados del HCHM, John Cerda.<\/p>\n<h2>Beneficios de la Queiloplast\u00eda<\/h2>\n<p>Los principales beneficios de esta cirug\u00eda para los ni\u00f1os son el retorno de la motricidad al labio superior, facilitando su amantamiento y alimentaci\u00f3n. \u201cPara los padres y la familia es muy importante, pues la cirug\u00eda produce un impacto positivo en su entorno porque cambia la apariencia facial del ni\u00f1o, mejorando con ello las condiciones para su desarrollo psicosocial posterior\u201d, resalt\u00f3 el Dr. Cerda.<br \/>\nTras esta operaci\u00f3n, el reci\u00e9n nacido debe asistir a controles peri\u00f3dicos con el comit\u00e9, que en nuestro Establecimiento funciona hace 24 a\u00f1os.<\/p>\n<h2>Prevenci\u00f3n de la fisura labiopalatina<\/h2>\n<p>Aunque esta enfermedad no es tan frecuente, s\u00ed requiere un tratamiento prolongado e integral, por lo que es fundamental prevenir su aparici\u00f3n, mediante los siguientes consejos:<br \/>\n1. Evitar la exposici\u00f3n de los padres a elementos medioambientales t\u00f3xicos, de uso agr\u00edcola o a drogas<br \/>\n2. No consumir ni alcohol ni tabaco durante el embarazo<br \/>\n3. Control de quienes ya han tenido un hijo con fisura labiopalatina, para prevenir una malformaci\u00f3n en el segundo embarazo.<br \/>\nEs considerada una patolog\u00eda con <a href=\"http:\/\/www.serviciodesaludnuble.cl\/sitio\/ges\/\" target=\"_blank\">Garant\u00edas Expl\u00edcitas en Salud <\/a>y puede detectarse con una ecograf\u00eda a partir de las 16 semanas de gestaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un equipo multidisciplinario controla y brinda atenci\u00f3n funcional y est\u00e9tica a los m\u00e1s de 300 \u00f1ublensinos que presentan fisura labiopalatina\u00a0(o de labio y paladar). Esta patolog\u00eda es una alteraci\u00f3n en la formaci\u00f3n de las estructuras de la cara, que requiere ser tratada desde el embarazo y hasta que la persona cumple 18 a\u00f1os, a lo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4507,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 13:13:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/4504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=4504"}],"version-history":[{"count":0,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/4504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/4507"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=4504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=4504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=4504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}