{"id":4396,"date":"2018-05-03T11:59:22","date_gmt":"2018-05-03T15:59:22","guid":{"rendered":"http:\/\/hospitaldechillan.cl\/web\/?p=4396"},"modified":"2018-05-04T15:36:27","modified_gmt":"2018-05-04T19:36:27","slug":"nuevos-especialistas-se-suman-a-la-atencion-en-el-hospital-de-chillan","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/nuevos-especialistas-se-suman-a-la-atencion-en-el-hospital-de-chillan\/","title":{"rendered":"Nuevos especialistas se suman a la atenci\u00f3n en el Hospital de Chill\u00e1n"},"content":{"rendered":"<p><strong>Oftalmolog\u00eda, Pediatr\u00eda, Cirug\u00eda Infantil, Neurocirug\u00eda, Traumatolog\u00eda, Medicina Familiar e Interna y oncolog\u00eda<\/strong> son algunas de las especialidades que se ven fortalecidas con la llegada de los 37 nuevos m\u00e9dicos, que se integran a la atenci\u00f3n del Centro Ambulatorio de Especialidades as\u00ed como tambi\u00e9n a los servicios de hospitalizados del Hospital Cl\u00ednico Herminda Mart\u00edn (HCHM).<\/p>\n<p>La mayor\u00eda de estos especialistas se incorporaron durante los primeros meses de 2018, por eso el Director del HCHM, Dr. Rodrigo Avenda\u00f1o Brandeis, se reuni\u00f3 con este grupo para darles la bienvenida junto con compartir el <a href=\"http:\/\/nuevohospitaldenuble.cl\/portal\/\" target=\"_blank\">proyecto asistencial<\/a> que actualmente desarrolla el principal centro de Salud de la nueva Regi\u00f3n de \u00d1uble. \u201cLa llegada de estos nuevos profesionales se enmarca en un plan de desarrollo que hemos efectuado con especial preocupaci\u00f3n durante los \u00faltimos cuatro a\u00f1os, el que nos ha permitido incorporar m\u00e1s de 100 especialistas al hospital, lo que sin duda se transforma en un valioso aporte, pues sus conocimientos nos permitir\u00e1n optimizar la atenci\u00f3n a las familias de \u00d1uble, disminuyendo la brecha existente en la zona\u201d, precis\u00f3 el Directivo.<\/p>\n<h2>Nuevos especialistas<\/h2>\n<p>El doctor Andr\u00e9s San Mart\u00edn, es penquista y especialista en Medicina Interna, actualmente se desempe\u00f1a en las unidades de Paciente Cr\u00edtico Adulto y M\u00e9dico Quir\u00fargico. Se form\u00f3 en el Hospital Cl\u00ednico de la Universidad de Chile y su decisi\u00f3n de incorporarse al HCHM estuvo marcada por su inter\u00e9s de regresar a la zona, \u201csiempre quise volver a esta Regi\u00f3n, por eso escog\u00ed el Hospital de Chill\u00e1n pues s\u00e9 que cuenta con la infraestructura y con el personal para ofrecer una buena medicina que permita salvar la vida de las personas\u201d, se\u00f1al\u00f3.<\/p>\n<p>De la misma manera, la especialista en Radiolog\u00eda e Im\u00e1genes, Sabrina\u00a0V\u00e1squez Bello, quien trabaja en el \u00e1rea ambulatoria y de urgencia, agradeci\u00f3 la recepci\u00f3n de la comunidad hospitalaria, pues \u201csomos varios especialistas venezolanos que llegamos al centro asistencial y valoramos la acogedora bienvenida que nos han brindado. Nuestro compromiso es entregar lo mejor de nuestras \u00e1reas para as\u00ed contribuir a mejorar la salud de las personas de la Regi\u00f3n\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oftalmolog\u00eda, Pediatr\u00eda, Cirug\u00eda Infantil, Neurocirug\u00eda, Traumatolog\u00eda, Medicina Familiar e Interna y oncolog\u00eda son algunas de las especialidades que se ven fortalecidas con la llegada de los 37 nuevos m\u00e9dicos, que se integran a la atenci\u00f3n del Centro Ambulatorio de Especialidades as\u00ed como tambi\u00e9n a los servicios de hospitalizados del Hospital Cl\u00ednico Herminda Mart\u00edn (HCHM). La [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4397,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 13:12:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/4396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=4396"}],"version-history":[{"count":0,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/4396\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/4397"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=4396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=4396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=4396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}