{"id":13629,"date":"2025-05-16T14:26:30","date_gmt":"2025-05-16T18:26:30","guid":{"rendered":"https:\/\/hospitaldechillan.cl\/web\/?p=13629"},"modified":"2025-05-16T14:26:30","modified_gmt":"2025-05-16T18:26:30","slug":"hospital-regional-de-nuble-ya-tiene-el-51-de-su-equipamiento-adjudicado","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/hospital-regional-de-nuble-ya-tiene-el-51-de-su-equipamiento-adjudicado\/","title":{"rendered":"Hospital Regional de \u00d1uble ya tiene el 51% de su equipamiento adjudicado"},"content":{"rendered":"<p>De los 65 mil millones de pesos destinados al equipamiento del nuevo <strong>Hospital Regional de \u00d1uble<\/strong>, el 51% ya ha sido adjudicado, evidenciando un avance en el proceso de implementaci\u00f3n. A esto se suman m\u00e1s de 11 mil millones de pesos que actualmente se encuentran en etapa de licitaci\u00f3n o evaluaci\u00f3n, lo que refleja el ritmo sostenido del proyecto para dotarlo de tecnolog\u00eda e infraestructura de alto est\u00e1ndar.<\/p>\n<p>La <strong>Dra. Luz Mar\u00eda Mor\u00e1n, Directora del Hospital Cl\u00ednico Herminda Mart\u00edn<\/strong>, sostiene que \u201ceste es uno de los proyectos de salud p\u00fablica m\u00e1s relevantes del pa\u00eds que transformar\u00e1 la atenci\u00f3n hospitalaria en el centro sur de Chile. El <strong>Hospital Regional de \u00d1uble <\/strong>alcanza un 95% de avance en su infraestructura, acerc\u00e1ndonos a un nuevo modelo de atenci\u00f3n centrado en las personas: m\u00e1s resolutivo, seguro y oportuno para la Regi\u00f3n\u201d.<\/p>\n<p>Este equipamiento representa un avance estrat\u00e9gico clave: \u201ctecnolog\u00edas de \u00faltima generaci\u00f3n que estar\u00e1n disponibles para la atenci\u00f3n p\u00fablica, como un resonador magn\u00e9tico y una piscina terap\u00e9utica, adem\u00e1s de TAC, mam\u00f3grafo y angi\u00f3grafo. Este progreso no solo refleja el cumplimiento del cronograma, sino que tambi\u00e9n permite proyectar una puesta en marcha eficiente y oportuna\u201d, agreg\u00f3 la directiva.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13632\" src=\"https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2025\/05\/2-1-640x360.png\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2025\/05\/2-1-640x360.png 640w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2025\/05\/2-1-1200x675.png 1200w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2025\/05\/2-1-768x432.png 768w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2025\/05\/2-1-1536x864.png 1536w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2025\/05\/2-1.png 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><strong>\u00bfEquipamiento o equipos cl\u00ednicos?<\/strong><\/p>\n<p>En la habilitaci\u00f3n del nuevo Hospital, es importante distinguir entre equipamiento y equipos cl\u00ednicos. El primero incluye todo lo que no requiere conexi\u00f3n el\u00e9ctrica y suele ser m\u00e1s numeroso: camillas, veladores cl\u00ednicos, cajas de instrumental quir\u00fargico o sillones dentales. Mientras que los segundos, son dispositivos de mayor tama\u00f1o y complejidad.<\/p>\n<p>Por su parte, <strong>Elizabeth Abarca Trivi\u00f1o, Directora del Servicio de Salud \u00d1uble, <\/strong>enfatiza en que \u201cestamos construyendo un hospital con equipamiento de alto est\u00e1ndar, desde m\u00e1quinas de anestesia y microscopios para neurocirug\u00eda, hasta un completo sistema de hidroterapia y m\u00e1s de 700 millones solo en instrumental cl\u00ednico\u201d.<\/p>\n<p>\u201cA la fecha, se han adjudicado 33 mil millones en equipamiento y equipos cl\u00ednicos clave para unidades especializadas como Imagenolog\u00eda, Angiograf\u00eda, Neurocirug\u00eda y Rehabilitaci\u00f3n\u201d, precis\u00f3.<\/p>\n<p>Con m\u00e1s de 500 mil personas beneficiadas en \u00d1uble y regiones cercanas, el nuevo hospital no solo triplicar\u00e1 la superficie del actual Hospital Cl\u00ednico Herminda Mart\u00edn, sino que incorporar\u00e1 espacios amplios, con mejor iluminaci\u00f3n natural, patios de luz, climatizaci\u00f3n y tecnolog\u00eda de \u00faltima generaci\u00f3n, enmarcados en el concepto de arquitectura saludable.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una parte significativa del equipamiento m\u00e9dico y mobiliario ya adjudicado, el nuevo recinto hospitalario avanza de manera sostenida hacia su puesta en marcha.<\/p>\n","protected":false},"author":3,"featured_media":13631,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-13629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:47:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/13629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=13629"}],"version-history":[{"count":1,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/13629\/revisions"}],"predecessor-version":[{"id":13633,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/13629\/revisions\/13633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/13631"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=13629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=13629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=13629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}