{"id":10304,"date":"2022-10-07T14:29:09","date_gmt":"2022-10-07T18:29:09","guid":{"rendered":"https:\/\/hospitaldechillan.cl\/web\/?p=10304"},"modified":"2022-10-07T15:05:38","modified_gmt":"2022-10-07T19:05:38","slug":"celebramos-el-logro-de-pacientes-con-fisura-labiopalatina-en-el-dia-mundial-de-la-sonrisa","status":"publish","type":"post","link":"https:\/\/hospitaldechillan.cl\/web\/celebramos-el-logro-de-pacientes-con-fisura-labiopalatina-en-el-dia-mundial-de-la-sonrisa\/","title":{"rendered":"Celebramos el logro de pacientes con fisura labiopalatina en el D\u00eda Mundial de la Sonrisa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La sonrisa es un gesto universal que conecta a las personas y genera bienestar. Por ese motivo, el <strong>Comit\u00e9 de Fisurados del Hospital Cl\u00ednico Herminda Mart\u00edn<\/strong> quiso relevar esta efem\u00e9ride y reunir a un grupo de los 130 pacientes que actualmente est\u00e1n en tratamiento. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fisura labiopalatina (FLP) es una alteraci\u00f3n en el desarrollo de la cara que se produce en una etapa temprana de la gestaci\u00f3n y que comienza a tratarse desde el nacimiento hasta el alta m\u00e9dica, que puede ser alrededor de los 18 o 20 a\u00f1os. En el mundo nacen cada d\u00eda 540 beb\u00e9s con esta condici\u00f3n, mientras que en Chile son alrededor de 450 en un a\u00f1o, de los cuales 10 nacen en el Hospital de Chill\u00e1n. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el prop\u00f3sito de resaltar los logros y avances de los ni\u00f1os y ni\u00f1as con condici\u00f3n de labio fisurado a lo largo de su tratamiento y rehabilitaci\u00f3n, hoy fueron destacados junto a sus familias por el Comit\u00e9 de Fisurados, relevando la perseverancia con la que enfrentan el tratamiento que es extenso y que incluye unas 100 atenciones cada a\u00f1o y unas cinco cirug\u00edas en el proceso de Rehabilitaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/hospitaldechillan.cl\/web\/wp-content_Hos\/uploads\/2022\/10\/Dia-de-la-Sonrisa-4-640x360.jpg\" alt=\"\" class=\"wp-image-10306\" srcset=\"https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2022\/10\/Dia-de-la-Sonrisa-4-640x360.jpg 640w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2022\/10\/Dia-de-la-Sonrisa-4-1200x675.jpg 1200w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2022\/10\/Dia-de-la-Sonrisa-4-768x432.jpg 768w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2022\/10\/Dia-de-la-Sonrisa-4-1536x864.jpg 1536w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2022\/10\/Dia-de-la-Sonrisa-4-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>Director (s) del Hospital, Dr. Alexis Rojo<\/strong> se\u00f1al\u00f3 que \u201casociar el D\u00eda de la Sonrisa con las personas con condici\u00f3n de labio fisurado, es una pr\u00e1ctica en muchos partes del mundo, y nos parece la m\u00e1xima idea porque es la forma en que decimos que todas las sonrisas son lindas, que nos unimos y trabajamos por devolverla a cada uno de nuestros usuarios y usuarias\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El facultativo tambi\u00e9n destac\u00f3 el trabajo del Comit\u00e9 hospitalario que \u201cest\u00e1 comprometido en transformar la vida de personas, en especial ni\u00f1os y ni\u00f1as, con un tratamiento multidisciplinario, que no solo impacta en su salud y calidad de vida, tambi\u00e9n en su integraci\u00f3n social. Su trabajo integral, con calidez y profesionalismo, signific\u00f3 que fueran acreditados en el a\u00f1o 2008 y pasar a ser uno de los 10 centros de referencia a nivel nacional que se encarga del tratamiento de esta condici\u00f3n, desde el nacimiento hasta la alta integral del paciente\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/hospitaldechillan.cl\/web\/wp-content_Hos\/uploads\/2022\/10\/Dia-de-la-Sonrisa-2-640x360.jpg\" alt=\"\" class=\"wp-image-10307\" srcset=\"https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2022\/10\/Dia-de-la-Sonrisa-2-640x360.jpg 640w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2022\/10\/Dia-de-la-Sonrisa-2-1200x675.jpg 1200w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2022\/10\/Dia-de-la-Sonrisa-2-768x432.jpg 768w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2022\/10\/Dia-de-la-Sonrisa-2-1536x864.jpg 1536w, https:\/\/hospitaldechillan.cl\/web\/wp-content\/uploads\/2022\/10\/Dia-de-la-Sonrisa-2-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, <strong>Jocelin Jim\u00e9nez, enfermera coordinadora del Comit\u00e9<\/strong> coment\u00f3 que \u201cesta es una forma distinta de generar un lazo m\u00e1s cercano con pacientes que conocemos desde el d\u00eda de su nacimiento y a quienes acompa\u00f1amos durante una larga etapa de su vida. Hoy quisimos reunirnos con ellos y ellas y sus familias para decirles que deben continuar adelante por el camino de la rehabilitaci\u00f3n y que estamos disponibles para seguir a su lado hasta finalizar con \u00e9xito el tratamiento\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La enfermera destac\u00f3 adem\u00e1s que \u201cnosotros como Comit\u00e9 disponemos de las especialidades necesarias para el tratamiento y rehabilitaci\u00f3n, pero lograrla de forma satisfactoria no depende solo de nosotros, sino tambi\u00e9n de las familias y de las ni\u00f1as, ni\u00f1os y j\u00f3venes que tienen esta condici\u00f3n, a quienes animamos a seguir adelante con este proceso\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reuni\u00f3n que cont\u00f3 con globoflexia, show infantil de la \u201cT\u00eda Pollito\u201d, caritas pintadas gracias al equipo de la modalidad no convencional de Mi Jard\u00edn al Hospital, tambi\u00e9n consider\u00f3 el testimonio de Karina Vega, ex usuaria del Comit\u00e9 de Fisurados expuso su experiencia y resalt\u00f3 que &nbsp;\u201csi bien el proceso de rehabilitaci\u00f3n fue dif\u00edcil, pero estoy convencida que por algo nac\u00ed con fisura y por eso, escog\u00ed mi profesi\u00f3n como fonoaudi\u00f3loga. Estas celebraciones a uno lo impulsan a seguir creciendo, a tener mayores metas y a pensar que s\u00ed se puede avanzar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Karina <\/strong>tambi\u00e9n tuvo palabras de agradecimiento para sus familiares y por supuesto, para el equipo del Comit\u00e9 \u201cellos nos dieron las directrices para que pudi\u00e9ramos avanzar. Agradezco tambi\u00e9n al hospital. Espero que mi testimonio, sirva para las nuevas generaciones. Aqu\u00ed podemos ver que podemos sonre\u00edr como todos, pese a que en un inicio tuvi\u00e9ramos pocas esperanzas\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe destacar que el <strong>Comit\u00e9 de Fisurados tiene 28 a\u00f1os de trayectoria <\/strong>e \u00a0integra a 17 profesionales del \u00e1mbito de la cirug\u00eda maxilofacial, ortodoncia, odontopediatr\u00eda, rehabilitaci\u00f3n oral e implantolog\u00eda, periodoncia, cirug\u00eda pl\u00e1stica y gen\u00e9tica, psicolog\u00eda, fonoaudiolog\u00eda, kinesiolog\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Actualmente 130 personas se encuentran en tratamiento por esta condici\u00f3n con el equipo del Comit\u00e9 de fisurados del establecimiento. Anualmente cada usuario recibe unas cien atenciones como parte del tratamiento y rehabilitaci\u00f3n, que se inicia desde el nacimiento hasta los 18 o 20 a\u00f1os. <\/p>\n","protected":false},"author":3,"featured_media":10305,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-10304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:11:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/10304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/comments?post=10304"}],"version-history":[{"count":0,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/posts\/10304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media\/10305"}],"wp:attachment":[{"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/media?parent=10304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/categories?post=10304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitaldechillan.cl\/web\/wp-json\/wp\/v2\/tags?post=10304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}